{"id":1517,"count":1,"description":"","link":"https:\/\/nextr.in\/blog\/tag\/5-ai-research-tools-to-enhance-your-research\/","name":"5 AI Research Tools to Enhance Your Research","slug":"5-ai-research-tools-to-enhance-your-research","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/nextr.in\/blog\/wp-json\/wp\/v2\/tags\/1517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nextr.in\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/nextr.in\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/nextr.in\/blog\/wp-json\/wp\/v2\/posts?tags=1517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}